{"id":28625,"date":"2025-08-08T11:15:28","date_gmt":"2025-08-08T03:15:28","guid":{"rendered":"https:\/\/www.liandafiltration.com\/?p=28625"},"modified":"2025-10-15T10:00:33","modified_gmt":"2025-10-15T02:00:33","slug":"einfuhrung-von-metallfaltenfilterelementen","status":"publish","type":"post","link":"https:\/\/www.liandafiltration.com\/de\/einfuhrung-von-metallfaltenfilterelementen\/","title":{"rendered":"Einf\u00fchrung von Metallfaltenfilterelementen"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"28625\" class=\"elementor elementor-28625\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c127f5 e-flex e-con-boxed e-con e-parent\" data-id=\"7c127f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51be00e elementor-widget elementor-widget-heading\" data-id=\"51be00e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Faltenfilterelement aus Metall<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9de077b elementor-widget elementor-widget-text-editor\" data-id=\"9de077b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Metallfilterelemente werden in der Regel aus metallischen Filtermaterialien hergestellt und mit einer geschwei\u00dften Struktur montiert. <strong><a href=\"https:\/\/www.liandafiltration.com\/de\/produkt\/gesintertes-filterelement\/plissiertes-metall-filterelement\/\">Faltenfilterelemente aus Metall<\/a><\/strong> sind eine besondere Art von Metallfilterelementen, die die Filterfl\u00e4che pro Volumeneinheit durch Falten und Zusammenf\u00fcgen der Metallfiltermaterialien vergr\u00f6\u00dfern. Metallplissee-Filterelemente werden manchmal auch als Metallplissee-Wellenfilterelemente oder Metallwellenblatt-Filterelemente bezeichnet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9e20d1 elementor-widget elementor-widget-heading\" data-id=\"a9e20d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Welche Filtermaterialien k\u00f6nnen zur Herstellung verwendet werden? <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec8c604 elementor-widget elementor-widget-text-editor\" data-id=\"ec8c604\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><b>(1) Metalldrahtgewebe<\/b><\/strong>. Metalldrahtgewebe ist das gebr\u00e4uchlichste Metallfiltermaterial, das aus Metalldr\u00e4hten besteht, die zu einem Netzgewebe verwoben sind. Der Pr\u00e4zisionsbereich reicht von nominal 1 Mikrometer bis zu Hunderten von Mikrometern. Die Webstruktur und die Kombination von Kette und Schuss des Drahtgeflechts sind sehr flexibel und variabel, so dass die unterschiedlichen Anforderungen der verschiedenen Anwendungsbereiche erf\u00fcllt werden k\u00f6nnen. Aufgrund des Filterprinzips von Metalldrahtgewebe sind plissierte Filterelemente aus Metalldrahtgewebe oft leichter zu reinigen und zu regenerieren. Gleichzeitig sind Drahtgeflechtfilterelemente auch die wirtschaftlichste Art von Metallfilterelementen.<\/p><p><strong><b>(2) Metall gesintert <\/b><\/strong><strong><b>Faser<\/b><\/strong><strong><b>.<\/b><\/strong>\u00a0Die gesinterte Metallfaser ist ein dreidimensionales por\u00f6ses Metallfiltermaterial, das durch die ungeordnete Verlegung mikrometergro\u00dfer Metallfasern gebildet wird, \u00e4hnlich wie ein Vliesstoff. Ihr Pr\u00e4zisionsbereich liegt zwischen 3 und 100 Mikrometern. Gesinterte Metallfasern haben die Eigenschaft der Tiefenfiltration und verf\u00fcgen \u00fcber eine h\u00f6here Schadstoffaufnahmekapazit\u00e4t. Ein weiteres herausragendes Merkmal der Sinterfaser ist ihre extrem hohe Porosit\u00e4t (in der Regel 70% bis 80%), wodurch sie einen geringeren Druckverlust aufweist und sich besser f\u00fcr die Filtration von Fl\u00fcssigkeiten mit hoher Viskosit\u00e4t eignet.<\/p><p><strong><b>(3) Metall gesintert <\/b><\/strong><strong><b>Netz<\/b><\/strong><strong><b>.<\/b><\/strong>\u00a0Sintergewebe ist ein mehrlagiges Drahtgeflecht, das durch die Kombination mehrerer Lagen von Drahtgeflechten durch Sintern entsteht. Normalerweise sind Sintergewebe nicht gefaltet, aber durch eine spezielle Drahtauswahl und -konstruktion k\u00f6nnen gefaltete Sintermetallgewebe hergestellt werden. Gesinterte, gefaltete Filterelemente aus Metall haben die gleichen Eigenschaften wie gefaltete Filterelemente aus Metalldrahtgeflecht, erreichen aber auch eine h\u00f6here Festigkeit und eine l\u00e4ngere Lebensdauer und sind eine bessere L\u00f6sung f\u00fcr besondere Arbeitsbedingungen oder spezifische Anforderungen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ae8d71 elementor-widget elementor-widget-heading\" data-id=\"3ae8d71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wie ist sie aufgebaut? <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8ff29b elementor-widget elementor-widget-text-editor\" data-id=\"b8ff29b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das voll ausgestattete Metallfaltenfilterelement hat im Allgemeinen den folgenden Aufbau:<br \/><br \/><strong><b>(1) Die Anschlusskappe<\/b><\/strong><strong><b>.<\/b><\/strong>\u00a0Es handelt sich um ein Metallteil, das f\u00fcr die Verbindung und Abdichtung des Filterelements mit dem Geh\u00e4use verwendet wird. G\u00e4ngige Formen sind 226 (Doppeldichtringe + Sicherungsfl\u00fcgel), 222 (Doppeldichtringe), NPT-Gewinde, M-Gewinde, DOE-Doppel\u00f6ffnungsende usw.<\/p><p><b><\/b><strong><b>(2) Die innere St\u00fctze <\/b><\/strong><strong><b>Kernst\u00fcck<\/b><\/strong><strong><b>.<\/b><\/strong>Es st\u00fctzt das gefaltete Filtermaterial von innen, um zu verhindern, dass es unter Druck zusammenbricht. In der Regel werden spiralperforierte Rohre oder perforierte Rohre mit gerader Naht verwendet. In Sonderausf\u00fchrungen werden auch Keildrahtrohre, Rundwickeldrahtrohre usw. als St\u00fctzrohr verwendet.<\/p><p><b><\/b><strong><b>(3) Die<\/b><\/strong><b><\/b><strong><b>\u00a0<\/b><\/strong><strong><b>plissierte Netzh\u00fclse<\/b><\/strong><strong><b>. <\/b><\/strong>Das Material hat in der Regel mindestens 3 Schichten: die innere Schutzschicht, die Hauptfilterschicht und die \u00e4u\u00dfere Schutzschicht. In Sonderausf\u00fchrungen k\u00f6nnen auch Dispersionsschichten oder Verst\u00e4rkungsschichten vorhanden sein. Die innere und die \u00e4u\u00dfere Schutzschicht bestehen in der Regel aus Drahtgewebe mit 30 bis 80 Maschen.<\/p><p><b><\/b><strong><b>(4) Der \u00e4u\u00dfere Schutz <\/b><\/strong><strong><b>K\u00e4fig<\/b><\/strong><strong><b>.<\/b><\/strong>Es bietet einen \u00e4u\u00dferen Schutz f\u00fcr das gefaltete Filtermaterial, um zu verhindern, dass es platzt oder sich verformt, wenn es dem Gegendruck ausgesetzt ist. Normalerweise werden quadratische oder runde perforierte Rohre mit gro\u00dfer \u00d6ffnungsrate, Drahtfedern oder Metallb\u00e4nder verwendet.<\/p><p><b><\/b><strong><b>(5) Der Boden <\/b><\/strong><strong><b>Kappe<\/b><\/strong>. Die Bodenkappe ist ein wesentlicher Bestandteil des einseitig \u00f6ffnenden Filterelements und dient sowohl der Dichtungsfunktion als auch der Positionierungs- und Hilfsmontagefunktion. Das untere Ende hat einen flachen Boden, einen sechseckigen Boden, mit Positionierungsfl\u00fcgeln, mit Positionierungsschrauben, usw.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94cbe18 elementor-widget elementor-widget-heading\" data-id=\"94cbe18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Die wichtigsten Vorteile: <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfd87b0 elementor-widget elementor-widget-text-editor\" data-id=\"bfd87b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>(1). Hohe Filtrationspr\u00e4zision<\/strong><br \/>Die plissierten Metallfilterkerzen k\u00f6nnen f\u00fcr verschiedene Filtrationsgrade von 3 bis 200 Mikron angepasst werden und erf\u00fcllen die Filtrationsanforderungen verschiedener Industrien, wie z. B. Trinkwasserreinigung, industrielle \u00d6lfiltration, Reinigung von chemischen Medien und Hochtemperaturgasfiltration.<br \/><br \/><strong>(2). Lange Nutzungsdauer<\/strong><br \/>Metallische Materialien haben eine ausgezeichnete Korrosionsbest\u00e4ndigkeit und mechanische Festigkeit, k\u00f6nnen hohen Temperaturen und hohem Druck standhalten und sind weniger anf\u00e4llig f\u00fcr Verformungen oder Besch\u00e4digungen. Im Vergleich zu herk\u00f6mmlichen PP-Baumwoll- oder Aktivkohlefilterpatronen k\u00f6nnen Metallfilterpatronen wiederholt gereinigt und wiederverwendet werden, was die H\u00e4ufigkeit des Austauschs und die Kosten erheblich reduziert.<\/p><p><strong>(3) Hoher Durchfluss, geringer Druckverlust.<\/strong><br \/>Die gefaltete Struktur erm\u00f6glicht es dem Filterelement, eine hohe Pr\u00e4zision beizubehalten und gleichzeitig eine gro\u00dfe Durchflussmenge zu liefern, was den Fl\u00fcssigkeitswiderstand reduziert und die Effizienz des Systems verbessert.<br \/><br \/><strong>(4). Umweltfreundlich und recycelbar<\/strong><br \/>Das Metallfilterelement kann vollst\u00e4ndig recycelt werden, wodurch die durch die Entsorgung herk\u00f6mmlicher Filterelemente verursachte Umweltverschmutzung vermieden wird, was im Einklang mit dem Konzept der gr\u00fcnen und nachhaltigen Entwicklung steht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f9fc6a9 e-con-full e-flex e-con e-child\" data-id=\"f9fc6a9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1684e7a e-con-full e-flex e-con e-child\" data-id=\"1684e7a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-09d3ab1 elementor-widget elementor-widget-image\" data-id=\"09d3ab1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.liandafiltration.com\/wp-content\/uploads\/2025\/05\/6-1.jpg\" class=\"attachment-large size-large wp-image-26614\" alt=\"Plissiertes Filterelement\" srcset=\"https:\/\/www.liandafiltration.com\/wp-content\/uploads\/2025\/05\/6-1.jpg 800w, https:\/\/www.liandafiltration.com\/wp-content\/uploads\/2025\/05\/6-1-300x300.jpg 300w, https:\/\/www.liandafiltration.com\/wp-content\/uploads\/2025\/05\/6-1-150x150.jpg 150w, https:\/\/www.liandafiltration.com\/wp-content\/uploads\/2025\/05\/6-1-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e0d6b5 e-con-full e-flex e-con e-child\" data-id=\"0e0d6b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62b0d68 elementor-widget elementor-widget-image\" data-id=\"62b0d68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.liandafiltration.com\/wp-content\/uploads\/2025\/05\/1-4.jpg\" class=\"attachment-large size-large wp-image-26609\" alt=\"Plissiertes Filterelement\" srcset=\"https:\/\/www.liandafiltration.com\/wp-content\/uploads\/2025\/05\/1-4.jpg 800w, https:\/\/www.liandafiltration.com\/wp-content\/uploads\/2025\/05\/1-4-300x300.jpg 300w, https:\/\/www.liandafiltration.com\/wp-content\/uploads\/2025\/05\/1-4-150x150.jpg 150w, https:\/\/www.liandafiltration.com\/wp-content\/uploads\/2025\/05\/1-4-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-476f84f elementor-widget elementor-widget-heading\" data-id=\"476f84f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> Anwendungsbereiche<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d7ef1d elementor-widget elementor-widget-text-editor\" data-id=\"7d7ef1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wasseraufbereitung f\u00fcr den Haushalt: Wird in hochwertigen Wasseraufbereitungsanlagen verwendet, um Rost, Sedimente und andere Partikel herauszufiltern und so saubereres und sichereres Trinkwasser zu erhalten.<br \/>Lebensmittel- und Getr\u00e4nkeindustrie: Filtern von Sirup, Saft, Bier usw., um die Produktreinheit zu gew\u00e4hrleisten.<br \/>Erd\u00f6l- und Chemieindustrie: f\u00fcr die Filtration von Kraftstoff und Schmier\u00f6l, zum Schutz der Anlagen vor Partikelverschlei\u00df.<br \/>Pharmazeutische Industrie: Filtern von fl\u00fcssigen Medikamenten in aseptischen Produktionsprozessen zur Sicherung der Arzneimittelqualit\u00e4t.<br \/>Elektronikindustrie: Aufbereitung von ultrareinem Wasser, um zu verhindern, dass winzige Partikel die elektronischen Pr\u00e4zisionsbauteile beeintr\u00e4chtigen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5fde4d8 e-flex e-con-boxed e-con e-parent\" data-id=\"5fde4d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3dc1743 elementor-widget elementor-widget-heading\" data-id=\"3dc1743\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wartung und Pflege<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a472921 elementor-widget elementor-widget-text-editor\" data-id=\"a472921\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das plissierte Metallfilterelement ist f\u00fcr R\u00fccksp\u00fclung, Ultraschallreinigung oder chemische Reinigung geeignet und kann nach Wiederherstellung der Filtrationsleistung wiederverwendet werden. Eine regelm\u00e4\u00dfige Wartung kann die Lebensdauer verl\u00e4ngern und die Betriebskosten senken.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c81d50 e-flex e-con-boxed e-con e-parent\" data-id=\"6c81d50\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b6a4f97 elementor-widget elementor-widget-heading\" data-id=\"b6a4f97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schlussfolgerung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1f1cfd elementor-widget elementor-widget-text-editor\" data-id=\"c1f1cfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das plissierte Metallfilterelement mit seiner hohen Effizienz, Haltbarkeit und Umweltfreundlichkeit ist zu einem repr\u00e4sentativen Produkt der modernen Filtrationstechnologie geworden. Ob es sich um die Wasseraufbereitung im Haushalt oder die industrielle Pr\u00e4zisionsfiltration handelt, es bietet stabile und zuverl\u00e4ssige L\u00f6sungen f\u00fcr die strengen Anforderungen der verschiedenen Szenarien. Wenn Sie sich f\u00fcr ein Metallfilterelement entscheiden, entscheiden Sie sich f\u00fcr eine lang anhaltende, hochwertige Filtrationserfahrung!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f4f9cf5 e-flex e-con-boxed e-con e-parent\" data-id=\"f4f9cf5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a4f441 elementor-widget elementor-widget-text-editor\" data-id=\"6a4f441\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ad6247 elementor-widget elementor-widget-heading\" data-id=\"1ad6247\" data-element_type=\"widget\" data-widget_type=\"heading.default\"><div class=\"elementor-widget-container\"><h2 class=\"elementor-heading-title elementor-size-default\">Kontaktieren Sie uns f\u00fcr Metallfaltenfilterelemente<\/h2><\/div><\/div><div class=\"elementor-element elementor-element-29a1564 elementor-widget elementor-widget-text-editor\" data-id=\"29a1564\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p data-start=\"4564\" data-end=\"4750\">Ob Sie nun Standard- oder kundenspezifische Filterelemente ben\u00f6tigen,\u00a0<strong data-start=\"4621\" data-end=\"4645\">Kontaktieren Sie LIANDA noch heute<\/strong>\u00a0um Ihre Projektanforderungen zu besprechen. Wir bieten schnelle Lieferung, technische Unterst\u00fctzung und wettbewerbsf\u00e4hige Preise.<\/p><p data-start=\"4752\" data-end=\"4847\">\ud83d\udc49\u00a0<strong data-start=\"4755\" data-end=\"4818\"><a class=\"cursor-pointer\" href=\"https:\/\/www.liandafiltration.com\/de\/kontakt\/\" target=\"_new\" rel=\"noopener\" data-start=\"4757\" data-end=\"4816\">Kontaktieren Sie uns jetzt<\/a><\/strong>\u00a0f\u00fcr ein Angebot oder eine Beratung.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7ca92e elementor-widget elementor-widget-wpforms\" data-id=\"f7ca92e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpforms-container\" id=\"wpforms-25709\"><form id=\"wpforms-form-25709\" class=\"wpforms-validate wpforms-form\" data-formid=\"25709\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/de\/wp-json\/wp\/v2\/posts\/28625\" data-token=\"2eed12f0c5894382a2c1af88a2e432e8\" data-token-time=\"1784077868\" data-trp-original-action=\"\/de\/wp-json\/wp\/v2\/posts\/28625\"><noscript class=\"wpforms-error-noscript\">Bitte aktivieren Sie JavaScript in Ihrem Browser, um dieses Formular fertigzustellen.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-25709-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-25709-field_0\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-25709-field_0\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][0]\" placeholder=\"Name\" required><\/div><div id=\"wpforms-25709-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-25709-field_1\">E-Mail <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-25709-field_1\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"E-Mail\" spellcheck=\"false\" required><\/div><div id=\"wpforms-25709-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-25709-field_2\">Kommentar oder Nachricht <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-25709-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Nennen Sie uns Ihren Bedarf\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-25709-field-hp\" class=\"wpforms-field-label\">E-Mail<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-25709-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"25709\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/posts\/28625\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-25709\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Send Message\" aria-live=\"assertive\" value=\"wpforms-submit\">Nachricht senden<\/button><\/div><input type=\"hidden\" name=\"trp-form-language\" value=\"de\"\/><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Metallplissee-Filterelement Metallfilterelemente werden in der Regel aus Metallfiltermaterialien hergestellt und mit einer Schwei\u00dfkonstruktion zusammengesetzt. Metallplissee-Filterelemente sind eine besondere Art von Metallfilterelementen, die die Filtrationsfl\u00e4che pro Volumeneinheit durch Plissieren und Zusammenf\u00fcgen der Metallfiltermaterialien vergr\u00f6\u00dfern. Metallplissee-Filterelemente werden manchmal auch Metallplissee-Wellenfilter genannt [...]<\/p>","protected":false},"author":1,"featured_media":26613,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21],"tags":[],"table_tags":[],"class_list":["post-28625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/posts\/28625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/comments?post=28625"}],"version-history":[{"count":10,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/posts\/28625\/revisions"}],"predecessor-version":[{"id":28666,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/posts\/28625\/revisions\/28666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/media\/26613"}],"wp:attachment":[{"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/media?parent=28625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/categories?post=28625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/tags?post=28625"},{"taxonomy":"table_tags","embeddable":true,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/table_tags?post=28625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}