{"id":29684,"date":"2026-05-27T11:39:46","date_gmt":"2026-05-27T03:39:46","guid":{"rendered":"https:\/\/www.liandafiltration.com\/?p=29684"},"modified":"2026-05-27T13:45:50","modified_gmt":"2026-05-27T05:45:50","slug":"filterplatte-aus-gesintertem-edelstahl","status":"publish","type":"post","link":"https:\/\/www.liandafiltration.com\/de\/filterplatte-aus-gesintertem-edelstahl\/","title":{"rendered":"Filterplatte aus gesintertem Edelstahl"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"29684\" class=\"elementor elementor-29684\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4321c8e e-flex e-con-boxed e-con e-parent\" data-id=\"4321c8e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ccd269 elementor-widget elementor-widget-heading\" data-id=\"7ccd269\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Filterplatte aus gesintertem Edelstahl<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f64be77 e-flex e-con-boxed e-con e-parent\" data-id=\"f64be77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-193a5c4 elementor-widget elementor-widget-text-editor\" data-id=\"193a5c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gesinterte Edelstahl-Filterplatten sind plattenf\u00f6rmige, por\u00f6se Filterelemente, die durch die Verdichtung von Edelstahl-Rohstoffen (entweder Pulver oder Drahtgeflecht) im Sinterverfahren hergestellt werden. Je nach den verwendeten Rohstoffen werden sie haupts\u00e4chlich in zwei Hauptkategorien unterteilt: gesinterte Edelstahl-Pulverfilterplatten und gesinterte Edelstahl-Drahtgewebe-Filterplatten. Gesinterte Pulverfilterplatten werden aus Edelstahlpulver als Rohstoff hergestellt, das durch Hochtemperatursintern verdichtet wird; por\u00f6se Filterplatten aus gesintertem Drahtgeflecht hingegen werden hergestellt, indem mehrere Lagen gewebten Edelstahlgewebes \u00fcbereinandergeschichtet und unter hohem Druck und hoher Temperatur gesintert werden, wobei die Maschen\u00f6ffnungen jeder Lage versetzt angeordnet sind, um eine porengr\u00f6\u00dfengradiente Struktur zu erzeugen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84ae907 elementor-widget elementor-widget-text-editor\" data-id=\"84ae907\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Da das Ausgangsmaterial f\u00fcr por\u00f6se, gesinterte Siebfilterplatten gewebtes Drahtgeflecht ist, weisen sie denselben Filtrationsgenauigkeitsbereich auf wie das Gewebe selbst und erreichen eine maximale Filterfeinheit von 1 Mikrometer. Im Gegensatz dazu unterliegt die Pr\u00e4zision pulversinterter Filterplatten nicht den Einschr\u00e4nkungen des Drahtgeflechts, was eine Filtergenauigkeit von bis zu 0,45 Mikrometern erm\u00f6glicht. Im Vergleich zu gewebtem Drahtgewebe bieten gesinterte Edelstahl-Filterplatten erhebliche Vorteile hinsichtlich struktureller Integrit\u00e4t und Konsistenz (da die gesinterte Platte eine monolithische Einheit bildet, bei der die Porenstruktur frei von Verformungen bleibt), mechanischer Festigkeit und Leistungsf\u00e4higkeit unter extremen Betriebsbedingungen (insbesondere ist die Druckfestigkeit von gesinterten Filterplatten deutlich h\u00f6her als die von ungesintertem Edelstahl-Drahtgewebe).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a2f36a elementor-widget elementor-widget-text-editor\" data-id=\"6a2f36a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dank ihrer Best\u00e4ndigkeit gegen hohe Temperaturen, hohen Druck und Korrosion finden Filterplatten aus gesintertem Edelstahl in den folgenden Branchen breite Anwendung:<br \/>Petrochemische Industrie: Einsatz in katalytischen Krackanlagen zur Hochtemperatur-Gasverteilung und zur Hochdruck-R\u00fccksp\u00fclfiltration;<br \/>Sie spielen eine zentrale Rolle bei Prozessen wie der Verarbeitung von Polymerschmelzen, der Katalysatorr\u00fcckgewinnung und der L\u00f6sungsmittelreinigung.<br \/>Lebensmittel- und Pharmaindustrie: Sie werden zur Pr\u00e4zisionsfiltration fl\u00fcssiger Lebensmittel \u2013 darunter Fruchts\u00e4fte, Sirupe und Speise\u00f6le \u2013 eingesetzt, um die Reinheit der Produkte zu gew\u00e4hrleisten; in der pharmazeutischen Produktion werden sie zur Sterilfiltration von Fermentationsbr\u00fchen und zur Feinfiltration von Injektionsl\u00f6sungen verwendet.<br \/>Wasseraufbereitung und Umweltschutz: Einsatz in Bereichen wie der industriellen Abwasseraufbereitung und der Vorbehandlung bei der Meerwasserentsalzung.<br \/>Energie und aufstrebende Branchen: Einsatz bei der Feinfiltration von Elektrolyten in der Lithium-Ionen-Batterieproduktion; zur Gasreinigung in Wasserstoff-Brennstoffzellen; sowie in der Luft- und Raumfahrt zur Reinigung von Hydraulikfl\u00fcssigkeiten und zur Kraftstofffiltration.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"table_tags":[],"class_list":["post-29684","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/posts\/29684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/comments?post=29684"}],"version-history":[{"count":4,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/posts\/29684\/revisions"}],"predecessor-version":[{"id":29689,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/posts\/29684\/revisions\/29689"}],"wp:attachment":[{"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/media?parent=29684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/categories?post=29684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/tags?post=29684"},{"taxonomy":"table_tags","embeddable":true,"href":"https:\/\/www.liandafiltration.com\/de\/wp-json\/wp\/v2\/table_tags?post=29684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}