{"id":29684,"date":"2026-05-27T11:39:46","date_gmt":"2026-05-27T03:39:46","guid":{"rendered":"https:\/\/www.liandafiltration.com\/?p=29684"},"modified":"2026-05-27T13:45:50","modified_gmt":"2026-05-27T05:45:50","slug":"piastra-filtrante-in-acciaio-inox-sinterizzato","status":"publish","type":"post","link":"https:\/\/www.liandafiltration.com\/it\/piastra-filtrante-in-acciaio-inox-sinterizzato\/","title":{"rendered":"Piastra filtrante in acciaio inossidabile sinterizzato"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"29684\" class=\"elementor elementor-29684\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4321c8e e-flex e-con-boxed e-con e-parent\" data-id=\"4321c8e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ccd269 elementor-widget elementor-widget-heading\" data-id=\"7ccd269\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Piastra filtrante in acciaio inossidabile sinterizzato<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f64be77 e-flex e-con-boxed e-con e-parent\" data-id=\"f64be77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-193a5c4 elementor-widget elementor-widget-text-editor\" data-id=\"193a5c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le piastre filtranti in acciaio inossidabile sinterizzato sono elementi filtranti porosi a forma di piastra ottenuti dalla compattazione di materie prime in acciaio inossidabile (polvere o rete metallica) mediante un processo di sinterizzazione. A seconda delle materie prime utilizzate, si classificano principalmente in due grandi categorie: piastre filtranti in polvere di acciaio inossidabile sinterizzato e piastre filtranti in rete metallica di acciaio inossidabile sinterizzata. Le piastre filtranti in polvere sinterizzata sono prodotte utilizzando polvere di acciaio inossidabile come materia prima, che viene consolidata attraverso la sinterizzazione ad alta temperatura; al contrario, le piastre filtranti porose in rete metallica sinterizzata sono prodotte impilando pi\u00f9 strati di rete metallica in acciaio inossidabile e sinterizzandoli in condizioni di alta pressione e alta temperatura, in cui le aperture della rete di ogni strato sono sfalsate per creare una struttura con pori di dimensioni graduate.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84ae907 elementor-widget elementor-widget-text-editor\" data-id=\"84ae907\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Poich\u00e9 la materia prima delle piastre filtranti in rete sinterizzata porosa \u00e8 la rete metallica intrecciata, esse presentano lo stesso intervallo di precisione di filtrazione della rete stessa, raggiungendo un massimo di 1 micron. Al contrario, la precisione delle piastre filtranti sinterizzate in polvere non \u00e8 vincolata dai limiti della tessitura della rete metallica, consentendo una precisione di filtrazione fino a 0,45 micron. Rispetto alla rete metallica, le piastre filtranti in acciaio inossidabile sinterizzato offrono vantaggi significativi in termini di integrit\u00e0 strutturale e uniformit\u00e0 (poich\u00e9 la piastra sinterizzata forma un'unit\u00e0 monolitica in cui la struttura porosa rimane priva di deformazioni), resistenza meccanica e prestazioni in condizioni operative estreme (in particolare, la resistenza alla pressione delle piastre filtranti sinterizzate \u00e8 significativamente superiore a quella della rete metallica in acciaio inossidabile non sinterizzata).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a2f36a elementor-widget elementor-widget-text-editor\" data-id=\"6a2f36a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Grazie alla loro resistenza alle alte temperature, alle alte pressioni e alla corrosione, le piastre filtranti in acciaio inossidabile sinterizzato trovano ampio impiego nei seguenti settori:<br \/>Industria petrolchimica: impiegato in impianti di cracking catalitico per la distribuzione di gas ad alta temperatura e la filtrazione a controlavaggio ad alta pressione;<br \/>Svolgono un ruolo fondamentale in processi quali la lavorazione dei polimeri fusi, il recupero dei catalizzatori e la purificazione dei solventi.<br \/>Settori alimentare e farmaceutico: utilizzati per la filtrazione di precisione di prodotti alimentari liquidi \u2014 tra cui succhi di frutta, sciroppi e oli alimentari \u2014 al fine di garantire la purezza del prodotto; nella produzione farmaceutica, vengono impiegati per la filtrazione sterile di brodi di fermentazione e per la filtrazione fine di soluzioni iniettabili.<br \/>Trattamento delle acque e tutela dell'ambiente: trova applicazione in contesti quali il trattamento delle acque reflue industriali e il pretrattamento per la desalinizzazione dell'acqua di mare.<br \/>Settore energetico e settori emergenti: utilizzati per la filtrazione di precisione degli elettroliti nella produzione di batterie agli ioni di litio; per la purificazione dei gas nelle celle a combustibile a idrogeno; e nel settore aerospaziale per la purificazione dei fluidi idraulici per l'aviazione e la filtrazione del carburante.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"table_tags":[],"class_list":["post-29684","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.liandafiltration.com\/it\/wp-json\/wp\/v2\/posts\/29684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.liandafiltration.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.liandafiltration.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.liandafiltration.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.liandafiltration.com\/it\/wp-json\/wp\/v2\/comments?post=29684"}],"version-history":[{"count":4,"href":"https:\/\/www.liandafiltration.com\/it\/wp-json\/wp\/v2\/posts\/29684\/revisions"}],"predecessor-version":[{"id":29689,"href":"https:\/\/www.liandafiltration.com\/it\/wp-json\/wp\/v2\/posts\/29684\/revisions\/29689"}],"wp:attachment":[{"href":"https:\/\/www.liandafiltration.com\/it\/wp-json\/wp\/v2\/media?parent=29684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.liandafiltration.com\/it\/wp-json\/wp\/v2\/categories?post=29684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.liandafiltration.com\/it\/wp-json\/wp\/v2\/tags?post=29684"},{"taxonomy":"table_tags","embeddable":true,"href":"https:\/\/www.liandafiltration.com\/it\/wp-json\/wp\/v2\/table_tags?post=29684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}